{"id":25,"count":1,"description":"","link":"https:\/\/orexis.io\/goetheanisten\/category\/imagination\/","name":"Imagination","slug":"imagination","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/orexis.io\/goetheanisten\/wp-json\/wp\/v2\/categories\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orexis.io\/goetheanisten\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/orexis.io\/goetheanisten\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/orexis.io\/goetheanisten\/wp-json\/wp\/v2\/posts?categories=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}